{"id":13819,"date":"2015-01-25T14:17:03","date_gmt":"2015-01-25T14:17:03","guid":{"rendered":"http:\/\/www.tligradio.org\/multisite3\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg"},"modified":"2015-01-25T14:17:03","modified_gmt":"2015-01-25T14:17:03","slug":"handwritten-messages-2-2","status":"inherit","type":"attachment","link":"https:\/\/tligradio.org\/lv\/handwritten-messages-2-2\/","title":{"rendered":"handwritten messages"},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-13819","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a data-rel=\"iLightbox[postimages]\" data-title=\"\" data-caption=\"\" href=\"https:\/\/i0.wp.com\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg?ssl=1\"><img decoding=\"async\" width=\"300\" height=\"109\" src=\"https:\/\/i0.wp.com\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg?fit=300%2C109&amp;ssl=1\" class=\"attachment-medium size-medium lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27960%27%20height%3D%27350%27%20viewBox%3D%270%200%20960%20350%27%3E%3Crect%20width%3D%27960%27%20height%3D%27350%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/i0.wp.com\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg?fit=300%2C109&amp;ssl=1\" data-srcset=\"https:\/\/i0.wp.com\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg?resize=300%2C109&amp;ssl=1 300w, https:\/\/i0.wp.com\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg?resize=768%2C280&amp;ssl=1 768w, https:\/\/i0.wp.com\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg?fit=960%2C350&amp;ssl=1 960w\" data-sizes=\"auto\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":350,"file":"2015\/01\/handwritten-messages1.jpg","sizes":{"thumbnail":{"file":"handwritten-messages1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"handwritten-messages1-300x109.jpg","width":300,"height":109,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg?fit=300%2C109&ssl=1"},"medium_large":{"file":"handwritten-messages1-768x280.jpg","width":768,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg?fit=768%2C280&ssl=1"},"risen-header":{"file":"handwritten-messages1-960x250.jpg","width":960,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1-960x250.jpg"},"risen-big-thumb":{"file":"handwritten-messages1-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1-600x400.jpg"},"risen-square-thumb":{"file":"handwritten-messages1-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1-180x180.jpg"},"risen-tiny-thumb":{"file":"handwritten-messages1-55x55.jpg","width":55,"height":55,"mime_type":"image\/jpeg","source_url":"https:\/\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1-55x55.jpg"},"full":{"file":"handwritten-messages1.jpg?fit=960%2C350&ssl=1","width":960,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg?fit=960%2C350&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/tligradio.org\/wp-content\/uploads\/2015\/01\/handwritten-messages1.jpg","_links":{"self":[{"href":"https:\/\/tligradio.org\/lv\/wp-json\/wp\/v2\/media\/13819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tligradio.org\/lv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/tligradio.org\/lv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/tligradio.org\/lv\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/tligradio.org\/lv\/wp-json\/wp\/v2\/comments?post=13819"}]}}