{"id":12625,"date":"2017-02-13T00:00:00","date_gmt":"2017-02-13T00:00:00","guid":{"rendered":"https:\/\/tligradio.org\/2017\/02\/mensaje-de-la-vved-dictado-a-vassula-el-13-de-febrero-de-2016-para-ser-publicado-inmediatamente\/"},"modified":"2021-03-20T12:51:53","modified_gmt":"2021-03-20T12:51:53","slug":"mensaje-de-la-vved-dictado-a-vassula-el-13-de-febrero-de-2016-para-ser-publicado-inmediatamente","status":"publish","type":"post","link":"https:\/\/tligradio.org\/es\/2017\/02\/mensaje-de-la-vved-dictado-a-vassula-el-13-de-febrero-de-2016-para-ser-publicado-inmediatamente\/","title":{"rendered":"Mensaje de la VVeD dictado a Vassula el 13 de febrero de 2016, para ser publicado inmediatamente"},"content":{"rendered":"<p>Mi paz te doy; \u00bfquieres anotar Mis Palabras?<\/p>\n<p>S\u00ed, Se\u00f1or\u2026<\/p>\n<p>esta generaci\u00f3n es dif\u00edcil de doblegar; debilitada por sus pecados, depositan su confianza en Satan\u00e1s, construyendo su esperanza en \u00e9l; aunque Me he presentado ante todos para que Me vieran, pocos se han dado cuenta; sus dirigentes se han vuelto crueles, y la muerte aguarda a muchas naciones por mano de ellos; \u00a1cu\u00e1nto he llorado sobre ti, generaci\u00f3n! T\u00fa, cuya vida se precipitar\u00e1 ahora hacia la muerte; luego, cuando las llamas laman como lenguas a tus habitantes, estallando en el aire, Yo preguntar\u00e9 a esta generaci\u00f3n:\u00bfd\u00f3nde encontrar\u00e1s alivio? \u00bfy en qui\u00e9n? \u00bfen Satan\u00e1s? \u00bfen tu ego y tu yo?<\/p>\n<p>ha llegado la hora de poner por obra Mi Justicia, porque el castigo de esta generaci\u00f3n infiel est\u00e1 a vuestras puertas; ejecutar\u00e9 Mis \u00f3rdenes a la letra; cuando oig\u00e1is el estallido del trueno, se oir\u00e1 Mi Voz, retumbando en vuestros o\u00eddos, resonando hasta los confines de la tierra; sabed entonces que el mundo y todo lo que vive en \u00e9l, oir\u00e1 la Voz de la Justicia: el mal traer\u00e1 la muerte a muchas naciones\u2026 la ruina se infiltrar\u00e1 en cada ciudad;<\/p>\n<p>\u00bfhab\u00e9is o\u00eddo que \u2018el \u00c1ngel de Yahveh cercar\u00e1 ciudades y naciones\u2019 llamando a cada uno al arrepentimiento? \u00e9stas son las cosas que suceder\u00e1n en los d\u00edas venideros;<\/p>\n<p>por lo tanto, vosotros que hab\u00e9is entrado en Mis Atrios y cre\u00eddo en Mis palabras, orad y no teng\u00e1is temor ni miedo; pero vosotros que os hab\u00e9is burlado de Mis palabras durante a\u00f1os sin fin, golpeando a mis profetas con vuestra lengua, \u00a1cuidado! porque hab\u00e9is utilizado mentiras para justificar vuestras mentiras, hab\u00e9is enterrado ciertamente Mis Palabras en vuestra propia tumba; s\u00ed, en efecto, hab\u00e9is estado retorciendo Mis Palabras; pero vuestros pecados han creado un abismo entre vosotros y Yo; y ahora la Justica no ser\u00e1 retenida; os lo digo, m\u00e1s amargos ser\u00e1n vuestros d\u00edas venideros, cuando Yo me enfrente a vosotros\u2026 \u00a1orad y no permit\u00e1is que se os cierren los p\u00e1rpados por el sue\u00f1o!<\/p>\n<p>he aqu\u00ed como deb\u00e9is orar:<\/p>\n<p>Yahveh, Dios m\u00edo, que mi plegaria llegue hasta Ti,<br \/>\nescucha nuestro grito pidiendo misericordia y ayuda,<br \/>\nperdona a los que no tienen fe en Ti, Dios m\u00edo,<br \/>\nni tampoco confianza en Tu poder para salvarnos;<\/p>\n<p>no extingas las luces de nuestros d\u00edas,<br \/>\nhaciendo con ello que la tierra se marchite en un instante;<br \/>\nantes bien, por Tu Compasi\u00f3n Paternal.<br \/>\nten piedad de nosotros y perd\u00f3nanos;<br \/>\nno permitas que el maligno derrame nuestra sangre como agua;<br \/>\nperdona nuestra culpa, reprime Tu ira,<br \/>\nacord\u00e1ndote de nuestra flaqueza;<\/p>\n<p>cont\u00e9n a Tus \u00e1ngeles del desastre,<br \/>\nd\u00e1ndonos una oportunidad m\u00e1s de probar<br \/>\nque somos dignos de Tu Bondad;<br \/>\npongo mi confianza en Ti; am\u00e9n\u201d<\/p>\n<p>con qu\u00e9 alegr\u00eda recibir\u00e9 entonces esta oraci\u00f3n;\u00a1 esta oraci\u00f3n que Me har\u00e1 ceder! hija, bendecir\u00e9 a todos aquellos que digan sinceramente esta oraci\u00f3n; que se escuche esta profec\u00eda; \u2018el d\u00eda y la hora me pertenecen a M\u00ed, vuestro Dios\u2019, esto es lo que les dir\u00e1s a aquellos que te pregunten por el tiempo y la hora de Mi Justicia! el Amor te ama;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi paz te doy; \u00bfquieres anotar Mis Palabras? S\u00ed, Se\u00f1or\u2026 esta generaci\u00f3n es dif\u00edcil de doblegar; debilitada por sus pecados, depositan su confianza en Satan\u00e1s, construyendo su esperanza en \u00e9l; aunque Me he presentado ante  [&#8230;]<\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[677],"tags":[],"series":[],"class_list":["post-12625","post","type-post","status-publish","format-standard","hentry","category-announcements-es"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tligradio.org\/es\/wp-json\/wp\/v2\/posts\/12625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tligradio.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tligradio.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tligradio.org\/es\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/tligradio.org\/es\/wp-json\/wp\/v2\/comments?post=12625"}],"version-history":[{"count":0,"href":"https:\/\/tligradio.org\/es\/wp-json\/wp\/v2\/posts\/12625\/revisions"}],"wp:attachment":[{"href":"https:\/\/tligradio.org\/es\/wp-json\/wp\/v2\/media?parent=12625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tligradio.org\/es\/wp-json\/wp\/v2\/categories?post=12625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tligradio.org\/es\/wp-json\/wp\/v2\/tags?post=12625"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/tligradio.org\/es\/wp-json\/wp\/v2\/series?post=12625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}